{"id":2407,"date":"2018-06-20T11:23:31","date_gmt":"2018-06-20T11:23:31","guid":{"rendered":"http:\/\/turismourdaibai.com\/?page_id=2407"},"modified":"2023-03-16T07:58:30","modified_gmt":"2023-03-16T07:58:30","slug":"oficinas-turismo","status":"publish","type":"page","link":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/","title":{"rendered":"Oficinas de Turismo"},"content":{"rendered":"<div id='full_slider_1'  class='avia-fullwidth-slider main_color avia-shadow   avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap fullsize'  >\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_slideshow_full-931252f08c53700f2105c1d02e17876e\">\n#top #wrap_all .avia-slideshow .av-slideshow-caption.av-av_slideshow_full-931252f08c53700f2105c1d02e17876e__0 .avia-caption-title{\nfont-size:80px;\ncolor:#ffffff;\n}\n#top .avia-slideshow .av-slideshow-caption.av-av_slideshow_full-931252f08c53700f2105c1d02e17876e__0 .avia-caption-content{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-slideshow av-av_slideshow_full-931252f08c53700f2105c1d02e17876e avia-slideshow-featured av_slideshow_full avia-fade-slider av-slideshow-ui av-control-hidden av-no-slider-navigation av-hide-nav-arrows av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied   avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;fade&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:true,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 28.666666666667%;'><li  class='avia-slideshow-slide av-av_slideshow_full-931252f08c53700f2105c1d02e17876e__0  av-single-slide slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img class=\"wp-image-2415 avia-img-lazy-loading-not-2415\"  src='https:\/\/beta.turismourdaibai.com\/wp-content\/uploads\/2018\/06\/cabecera-informacion.jpg' width='1500' height='430' title='Informacion' alt='informacion'  itemprop=\"thumbnailUrl\"   \/><div class='av-section-color-overlay' style='opacity: 0.1; background-color: #000000; '><\/div><\/div><\/li><\/ul><div class='av-slideshow-caption av-av_slideshow_full-931252f08c53700f2105c1d02e17876e__0 caption_fullwidth caption_center'><div class=\"container caption_container\"><div class=\"slideshow_caption\"><div class=\"slideshow_inner_caption\"><div class=\"slideshow_align_caption\"><h2 class='avia-caption-title '  itemprop=\"name\" >INFORMACI\u00d3N TUR\u00cdSTICA<\/h2><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<div id='av_section_1'  class='avia-section av-av_section-2dcda1862a94bb522b437cf4f29dd74d main_color avia-section-default avia-no-shadow  avia-builder-el-1  el_after_av_slideshow_full  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2407'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf av_one_half  avia-builder-el-2  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-1d36c20d1167287526d046571eba3072\">\n#top .av-special-heading.av-av_heading-1d36c20d1167287526d046571eba3072{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-1d36c20d1167287526d046571eba3072 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-1d36c20d1167287526d046571eba3072 .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-1d36c20d1167287526d046571eba3072 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-1d36c20d1167287526d046571eba3072 av-special-heading-h2 custom-color-heading  avia-builder-el-3  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >OFICINA DE TURISMO DE BERMEO<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6>Lamera, s\/n<br \/>\nTel.: 94 617 91 54<\/h6>\n<h6><a href=\"mailto:turismoa@bermeo.eus\">turismoa@bermeo.eus<\/a><\/h6>\n<h6><a href=\"http:\/\/www.visitbermeo.eus\" target=\"_blank\" rel=\"noopener noreferrer\">www.visitbermeo.eus<\/a><\/h6>\n<h6><\/h6>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_half  avia-builder-el-5  el_after_av_one_half  el_before_av_one_half  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-e36d1131020c343a2d75822cde990e2e\">\n#top .av-special-heading.av-av_heading-e36d1131020c343a2d75822cde990e2e{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-e36d1131020c343a2d75822cde990e2e .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-e36d1131020c343a2d75822cde990e2e .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-e36d1131020c343a2d75822cde990e2e .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-e36d1131020c343a2d75822cde990e2e av-special-heading-h2 custom-color-heading  avia-builder-el-6  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >OFICINA DE TURISMO DE MUNDAKA<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6>Joseba Deuna, s\/n<br \/>\nTel.: 94 617 72 01<\/h6>\n<h6><a href=\"mailto:turismo.mundaka@bizkaia.org\">turismo.mundaka@bizkaia.org<\/a><\/h6>\n<h6><a href=\"http:\/\/www.mundakaturismo.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.mundakaturismo.com<\/a><\/h6>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-15d750bd1b332b34c6e70b077ebbccdf av_one_half  avia-builder-el-8  el_after_av_one_half  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-887fe117fff917f20877ec8c8dfcbeb2\">\n#top .av-special-heading.av-av_heading-887fe117fff917f20877ec8c8dfcbeb2{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-887fe117fff917f20877ec8c8dfcbeb2 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-887fe117fff917f20877ec8c8dfcbeb2 .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-887fe117fff917f20877ec8c8dfcbeb2 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-887fe117fff917f20877ec8c8dfcbeb2 av-special-heading-h2 custom-color-heading  avia-builder-el-9  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >OFICINA DE TURISMO DE GERNIKA-LUMO<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-10587 alignnone\" style=\"font-size: 16px; line-height: 1.5;\" src=\"https:\/\/turismourdaibai.com\/wp-content\/uploads\/2019\/06\/Qcalidad-turistica.jpg\" alt=\"Qcalidad-turistica\" width=\"40\" height=\"40\" srcset=\"https:\/\/beta.turismourdaibai.com\/wp-content\/uploads\/2019\/06\/Qcalidad-turistica.jpg 80w, https:\/\/beta.turismourdaibai.com\/wp-content\/uploads\/2019\/06\/Qcalidad-turistica-36x36.jpg 36w\" sizes=\"(max-width: 40px) 100vw, 40px\" \/><\/h6>\n<h6>Artekale, 8<br \/>\nTel.: 94 625 58 92<br \/>\n<a href=\"mailto:turismo@gernika-lumo.eus\">turismo@gernika-lumo.eus<\/a><\/h6>\n<h6><a href=\"https:\/\/gernikainfo.eus\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.gernikainfo.eus<\/a><\/h6>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_half-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_half  avia-builder-el-11  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-7fcf415b9afe6642a59679a80bed3a79\">\n#top .av-special-heading.av-av_heading-7fcf415b9afe6642a59679a80bed3a79{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-7fcf415b9afe6642a59679a80bed3a79 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-7fcf415b9afe6642a59679a80bed3a79 .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-7fcf415b9afe6642a59679a80bed3a79 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-7fcf415b9afe6642a59679a80bed3a79 av-special-heading-h2 custom-color-heading  avia-builder-el-12  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >GESTI\u00d3N TUR\u00cdSTICA COMARCAL- URREMENDI<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6>Plaza Domingo Alegr\u00eda s\/n<\/h6>\n<h6>Gernika-Lumo<\/h6>\n<h6>Tel.: 946257609<\/h6>\n<h6><a href=\"mailto:urremendi@urremendi.org\">urremendi@urremendi.org<\/a><\/h6>\n<h6><a href=\"http:\/\/turismourdaibai.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.turismourdaibai.com<\/a><\/h6>\n<\/div><\/section><\/p><\/div><\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av_section_2'  class='avia-section av-av_section-2dcda1862a94bb522b437cf4f29dd74d main_color avia-section-default avia-no-shadow  avia-builder-el-14  el_after_av_section  el_before_av_section  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2407'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_full-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_one_full-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_full-15d750bd1b332b34c6e70b077ebbccdf av_one_full  avia-builder-el-15  el_before_av_two_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-faf6993da7688f33d6b1da225b0635cb\">\n#top .av-special-heading.av-av_heading-faf6993da7688f33d6b1da225b0635cb{\npadding-bottom:10px;\ncolor:#000000;\n}\nbody .av-special-heading.av-av_heading-faf6993da7688f33d6b1da225b0635cb .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-faf6993da7688f33d6b1da225b0635cb .special-heading-inner-border{\nborder-color:#000000;\n}\n.av-special-heading.av-av_heading-faf6993da7688f33d6b1da225b0635cb .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-faf6993da7688f33d6b1da225b0635cb av-special-heading-h2 custom-color-heading  avia-builder-el-16  avia-builder-el-no-sibling '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >Abiertas en temporada<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_two_fifth-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_two_fifth-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_two_fifth-15d750bd1b332b34c6e70b077ebbccdf av_two_fifth  avia-builder-el-17  el_after_av_one_full  el_before_av_three_fifth  first flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d\">\n#top .av-special-heading.av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-eaf2c28380fa0b9f346c6f5ca257e70d av-special-heading-h2 custom-color-heading  avia-builder-el-18  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >PUNTO DE INFORMACI\u00d3N DE EA<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6>Donibane enparantza<br \/>\nTel.: 649 354 834<\/h6>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_three_fifth-c8fc129dc35fd1ae2a1e410224d39ea8 av_three_fifth  avia-builder-el-20  el_after_av_two_fifth  avia-builder-el-last  flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-af70ab1b0db246327b1f1dd7a72749a1\">\n#top .av-special-heading.av-av_heading-af70ab1b0db246327b1f1dd7a72749a1{\npadding-bottom:10px;\ncolor:#008bb2;\n}\nbody .av-special-heading.av-av_heading-af70ab1b0db246327b1f1dd7a72749a1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-av_heading-af70ab1b0db246327b1f1dd7a72749a1 .special-heading-inner-border{\nborder-color:#008bb2;\n}\n.av-special-heading.av-av_heading-af70ab1b0db246327b1f1dd7a72749a1 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-af70ab1b0db246327b1f1dd7a72749a1 av-special-heading-h2 custom-color-heading  avia-builder-el-21  el_before_av_textblock  avia-builder-el-first '><h2 class='av-special-heading-tag'  itemprop=\"headline\"  >PUNTO DE INFORMACI\u00d3N SAN JUAN DE GAZTELUGATXE<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-av_textblock-2bd894dbf2e4bf2c4acf98ce4fbf94aa '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h6>Mirador de la antigua carretera Bakio-Bermeo,<\/h6>\n<h6>Abierta en Navidades, Semana Santa y entre el 1 de junio y el 30 de septiembre.<\/h6>\n<\/div><\/section><\/p><\/div>\n<\/p>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_section-d6f9431259cac0dde4d85c3ccef79d9a\">\n.avia-section.av-av_section-d6f9431259cac0dde4d85c3ccef79d9a .av-section-color-overlay{\nopacity:0.5;\nbackground-color:#008bb2;\nbackground-image:url(https:\/\/beta.turismourdaibai.com\/wp-content\/themes\/enfold\/images\/background-images\/dots-mini-light.png);\nbackground-repeat:repeat;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-av_section-d6f9431259cac0dde4d85c3ccef79d9a main_color avia-section-default avia-no-border-styling  avia-builder-el-23  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll av-section-color-overlay-active container_wrap fullsize'  ><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-2407'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-758d955f1930a222dc9209f5e75755b1\">\n#top .av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1{\npadding-bottom:10px;\ncolor:#ffffff;\nfont-size:45px;\n}\nbody .av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .av-special-heading-tag{\nfont-size:45px;\n}\n.av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-av_heading-758d955f1930a222dc9209f5e75755b1 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-758d955f1930a222dc9209f5e75755b1 av-special-heading-h3 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-24  el_before_av_one_fourth  avia-builder-el-first  av-inherit-size'><h3 class='av-special-heading-tag'  itemprop=\"headline\"  >Y ADEM\u00c1S&#8230;<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-15d750bd1b332b34c6e70b077ebbccdf\">\n.flex_column.av-av_one_fourth-15d750bd1b332b34c6e70b077ebbccdf{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-15d750bd1b332b34c6e70b077ebbccdf av_one_fourth  avia-builder-el-25  el_after_av_heading  el_before_av_one_fourth  first flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-av_button-853669fb4ef37e5440e21ab1e79cc5e2-wrap avia-button-center  avia-builder-el-26  avia-builder-el-no-sibling '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-853669fb4ef37e5440e21ab1e79cc5e2\">\n#top #wrap_all .avia-button.av-av_button-853669fb4ef37e5440e21ab1e79cc5e2{\nbackground-color:#008bb2;\nborder-color:#008bb2;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/beta.turismourdaibai.com\/es\/alojamientos\/'  class='avia-button av-av_button-853669fb4ef37e5440e21ab1e79cc5e2 avia-icon_select-no avia-size-x-large avia-position-center'  ><span class='avia_iconbox_title' >DONDE DORMIR<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_fourth  avia-builder-el-27  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-av_button-1d5d3d7fa295254456f7276a04bcee00-wrap avia-button-center  avia-builder-el-28  avia-builder-el-no-sibling '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-1d5d3d7fa295254456f7276a04bcee00\">\n#top #wrap_all .avia-button.av-av_button-1d5d3d7fa295254456f7276a04bcee00{\nbackground-color:#008bb2;\nborder-color:#008bb2;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/beta.turismourdaibai.com\/es\/restaurantes-y-asadores\/'  class='avia-button av-av_button-1d5d3d7fa295254456f7276a04bcee00 avia-icon_select-no avia-size-x-large avia-position-center'  ><span class='avia_iconbox_title' >DONDE COMER<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_fourth  avia-builder-el-29  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-av_button-1fa23b4f0ab3342af551d4371d498faa-wrap avia-button-center  avia-builder-el-30  avia-builder-el-no-sibling '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-1fa23b4f0ab3342af551d4371d498faa\">\n#top #wrap_all .avia-button.av-av_button-1fa23b4f0ab3342af551d4371d498faa{\nbackground-color:#008bb2;\nborder-color:#008bb2;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/beta.turismourdaibai.com\/es\/de-compras-por-urdaibai\/'  class='avia-button av-av_button-1fa23b4f0ab3342af551d4371d498faa avia-icon_select-no avia-size-x-large avia-position-center'  ><span class='avia_iconbox_title' >COMPRAS<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8\">\n.flex_column.av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-av_one_fourth-c8fc129dc35fd1ae2a1e410224d39ea8 av_one_fourth  avia-builder-el-31  el_after_av_one_fourth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-av_button-82b5ba59e451638c3b79ffe7145a850d-wrap avia-button-center  avia-builder-el-32  avia-builder-el-no-sibling '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-82b5ba59e451638c3b79ffe7145a850d\">\n#top #wrap_all .avia-button.av-av_button-82b5ba59e451638c3b79ffe7145a850d{\nbackground-color:#008bb2;\nborder-color:#008bb2;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/beta.turismourdaibai.com\/es\/actividades\/'  class='avia-button av-av_button-82b5ba59e451638c3b79ffe7145a850d avia-icon_select-no avia-size-x-large avia-position-center'  ><span class='avia_iconbox_title' >ACTIVIDADES<\/span><\/a><\/div><\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oficinas de Turismo - Turismo Urdaibai \/ Web oficial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oficinas de Turismo - Turismo Urdaibai \/ Web oficial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Turismo Urdaibai \/ Web oficial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/Turismourdaibai\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-16T07:58:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/turismourdaibai.com\/wp-content\/uploads\/2019\/06\/Qcalidad-turistica.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@turismourdaibai\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/\",\"url\":\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/\",\"name\":\"Oficinas de Turismo - Turismo Urdaibai \/ Web oficial\",\"isPartOf\":{\"@id\":\"https:\/\/beta.turismourdaibai.com\/es\/#website\"},\"datePublished\":\"2018-06-20T11:23:31+00:00\",\"dateModified\":\"2023-03-16T07:58:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/beta.turismourdaibai.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oficinas de Turismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/beta.turismourdaibai.com\/es\/#website\",\"url\":\"https:\/\/beta.turismourdaibai.com\/es\/\",\"name\":\"Turismo Urdaibai \/ Web oficial\",\"description\":\"\u00bfQuieres conocer un universo natural en el que vivir experiencias \u00fanicas? Una cultura y un patrimonio cautivador; un paisaje seductor; rutas y turismo activo para todos los gustos\u2026\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/beta.turismourdaibai.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oficinas de Turismo - Turismo Urdaibai \/ Web oficial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/","og_locale":"es_ES","og_type":"article","og_title":"Oficinas de Turismo - Turismo Urdaibai \/ Web oficial","og_url":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/","og_site_name":"Turismo Urdaibai \/ Web oficial","article_publisher":"https:\/\/es-es.facebook.com\/Turismourdaibai\/","article_modified_time":"2023-03-16T07:58:30+00:00","og_image":[{"url":"https:\/\/turismourdaibai.com\/wp-content\/uploads\/2019\/06\/Qcalidad-turistica.jpg"}],"twitter_card":"summary_large_image","twitter_site":"@turismourdaibai","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/","url":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/","name":"Oficinas de Turismo - Turismo Urdaibai \/ Web oficial","isPartOf":{"@id":"https:\/\/beta.turismourdaibai.com\/es\/#website"},"datePublished":"2018-06-20T11:23:31+00:00","dateModified":"2023-03-16T07:58:30+00:00","breadcrumb":{"@id":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/beta.turismourdaibai.com\/es\/oficinas-turismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/beta.turismourdaibai.com\/es\/"},{"@type":"ListItem","position":2,"name":"Oficinas de Turismo"}]},{"@type":"WebSite","@id":"https:\/\/beta.turismourdaibai.com\/es\/#website","url":"https:\/\/beta.turismourdaibai.com\/es\/","name":"Turismo Urdaibai \/ Web oficial","description":"\u00bfQuieres conocer un universo natural en el que vivir experiencias \u00fanicas? Una cultura y un patrimonio cautivador; un paisaje seductor; rutas y turismo activo para todos los gustos\u2026","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beta.turismourdaibai.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/pages\/2407"}],"collection":[{"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/comments?post=2407"}],"version-history":[{"count":39,"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/pages\/2407\/revisions"}],"predecessor-version":[{"id":18771,"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/pages\/2407\/revisions\/18771"}],"wp:attachment":[{"href":"https:\/\/beta.turismourdaibai.com\/es\/wp-json\/wp\/v2\/media?parent=2407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}